{"id":18699,"date":"2024-07-01T02:25:39","date_gmt":"2024-07-01T00:25:39","guid":{"rendered":"https:\/\/grupoyllaconza.pe\/?post_type=product&#038;p=18699"},"modified":"2026-07-11T19:07:02","modified_gmt":"2026-07-11T17:07:02","slug":"cintillo-blanco-550x4-8mm-nylon-uv","status":"publish","type":"product","link":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/","title":{"rendered":"CINTILLO BLANCO 550X4.8MM &#8211; NYLON UV"},"content":{"rendered":"<h4><strong>CINTILLO BLANCO 550X4.8MM<\/strong><\/h4>\n<p>Cintillo blanco 550&#215;4.8mm nylon. dise\u00f1ado para ofrecer un amarre resistente y confiable. Ideal para organizar cableado, fijar accesorios y realizar instalaciones profesionales con un acabado limpio y seguro.<\/p>\n<ul>\n<li>Poliamida 66 natural \u2013 UV negro: poliamida 66 colores<\/li>\n<li>Inflamabilidad de la materia prima: UL 94 \u2013 V2<\/li>\n<li>Absorci\u00f3n de humedad: 2,7% \u2013 2,8% (23\u00b0C \u2013 50%RH)<\/li>\n<li>T. de trabajo (operaci\u00f3n): -40\u00b0C \u2013 + 85\u00b0C (-40\u00b0F \u2013 + 185\u00b0F)<\/li>\n<li>T. M\u00ednima de Instalaci\u00f3n: -10\u00b0C (14\u00b0F)<\/li>\n<li>T. M\u00e1xima Sostenible Por Poco Tiempo: + 110 \u00b0C (230\u00b0F)<\/li>\n<li>Buena resistencia a bases, aceites, grasas, derivados de aceites, solventes de cloruro.<\/li>\n<li>Resistencia limitada a los \u00e1cidos. No es resistente a los finoles<\/li>\n<\/ul>\n<p><strong>CINTILLO BLANCO\u00a0<a href=\"https:\/\/grupoyllaconza.pe\/index.php\/product-tag\/4-8mm\/\">MEDIDAS<\/a><\/strong><\/p>\n<table width=\"1177\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"80\">Item No.<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"178\">L<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"80\">W<br \/>\nSize (mm)<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"87\">Tensile<br \/>\nStrength<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"116\">Min. Bundle<br \/>\nDiameter (mm)<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"120\">Max. Bundle<br \/>\nDiameter (mm)<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"115\">Min. Bundle<br \/>\nDiameter (in)<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"123\">Max. Bundle<br \/>\nDiameter (in)<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"109\">UV Resistant<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"89\">UL Type<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"80\">Serie<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">Size (mm)<\/td>\n<td style=\"text-align: center;\">Size (in)<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>NCT-200C<\/td>\n<td style=\"text-align: center;\">200&#215;4.8<\/td>\n<td style=\"text-align: center;\">8.0<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">49.50<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">1.95<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<td style=\"text-align: center;\" rowspan=\"13\">Serie C<\/td>\n<\/tr>\n<tr>\n<td>NCT-250C<\/td>\n<td style=\"text-align: center;\">250&#215;4.8<\/td>\n<td style=\"text-align: center;\">10.0<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">65.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">2.56<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-300C<\/td>\n<td style=\"text-align: center;\">300&#215;4.8<\/td>\n<td style=\"text-align: center;\">11.8<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">81.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">3.19<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-350C<\/td>\n<td style=\"text-align: center;\">350&#215;4.8<\/td>\n<td style=\"text-align: center;\">13.7<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">97.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">3.82<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-380C<\/td>\n<td style=\"text-align: center;\">380&#215;4.8<\/td>\n<td style=\"text-align: center;\">15.0<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">106.70<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">4.20<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-400C<\/td>\n<td style=\"text-align: center;\">400&#215;4.8<\/td>\n<td style=\"text-align: center;\">15.7<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">113.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">4.44<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-430C<\/td>\n<td style=\"text-align: center;\">430&#215;4.8<\/td>\n<td style=\"text-align: center;\">17.0<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">122.50<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">4.82<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-450C<\/td>\n<td style=\"text-align: center;\">450&#215;4.8<\/td>\n<td style=\"text-align: center;\">17.7<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">129.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">5.08<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-500C<\/td>\n<td style=\"text-align: center;\">500&#215;4.8<\/td>\n<td style=\"text-align: center;\">19.7<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">145.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">5.71<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-530C<\/td>\n<td style=\"text-align: center;\">530&#215;4.8<\/td>\n<td style=\"text-align: center;\">20.8<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">151.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">6.02<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-550C<\/td>\n<td style=\"text-align: center;\">550&#215;4.8<\/td>\n<td style=\"text-align: center;\">21.6<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">160.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">6.30<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-610C<\/td>\n<td style=\"text-align: center;\">610&#215;4.8<\/td>\n<td style=\"text-align: center;\">24.0<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">179.90<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">7.08<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td>NCT-750C<\/td>\n<td style=\"text-align: center;\">750&#215;4.8<\/td>\n<td style=\"text-align: center;\">29.0<\/td>\n<td style=\"text-align: center;\">4.8<\/td>\n<td style=\"text-align: center;\">23Kg (50lb)<\/td>\n<td style=\"text-align: center;\">3.50<\/td>\n<td style=\"text-align: center;\">220.00<\/td>\n<td style=\"text-align: center;\">0.14<\/td>\n<td style=\"text-align: center;\">8.66<\/td>\n<td style=\"text-align: center;\">Blanco<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong><a href=\"https:\/\/grupoyllaconza.com.pe\/product-category\/cintillo-blanco\/\">MAS CINTILLOS NYLON<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/grupoyllaconza.pe\/wp-content\/uploads\/2026\/07\/ficha-tecnica-cintillo-nylon-emecx.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-11168\" src=\"http:\/\/grupoyllaconza.com.pe\/wp-content\/uploads\/2021\/01\/botoon-300x98.png\" alt=\"\" width=\"239\" height=\"78\" \/><\/a><\/p>\n","protected":false},"featured_media":20937,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[189],"product_tag":[193,195],"class_list":["post-18699","product","type-product","status-publish","has-post-thumbnail","product_cat-cintillo-blanco","product_tag-4-8mm","product_tag-nylon","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-after_add_to_cart"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Grupo Yllaconza - Sitio Web\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CINTILLO BLANCO 550X4.8MM \u2013 NYLON UV - Grupo Yllaconza\" \/>\n\t\t<meta property=\"og:description\" content=\"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-01T00:25:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-11T17:07:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CINTILLO BLANCO 550X4.8MM \u2013 NYLON UV - Grupo Yllaconza\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/grupoyllaconza.pe\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/shop-2\\\/#listItem\",\"name\":\"Shop Page\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/shop-2\\\/#listItem\",\"position\":2,\"name\":\"Shop Page\",\"item\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/shop-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product-category\\\/cintillo-blanco\\\/#listItem\",\"name\":\"CINTILLO BLANCO\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product-category\\\/cintillo-blanco\\\/#listItem\",\"position\":3,\"name\":\"CINTILLO BLANCO\",\"item\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product-category\\\/cintillo-blanco\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#listItem\",\"name\":\"CINTILLO BLANCO 550X4.8MM &#8211; NYLON UV\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/shop-2\\\/#listItem\",\"name\":\"Shop Page\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#listItem\",\"position\":4,\"name\":\"CINTILLO BLANCO 550X4.8MM &#8211; NYLON UV\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product-category\\\/cintillo-blanco\\\/#listItem\",\"name\":\"CINTILLO BLANCO\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#itempage\",\"url\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/\",\"name\":\"CINTILLO BLANCO 550X4.8MM \\u2013 NYLON UV - Grupo Yllaconza\",\"description\":\"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\\u00f3n. Ideal para instalaciones el\\u00e9ctricas, industriales y comerciales ...\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/grupoyllaconza.pe\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/CINTILLO-BLANCO-550-X-4.8MM-NYLON-scaled.jpg\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#mainImage\",\"width\":2560,\"height\":2560,\"caption\":\"CINTILLO BLANCO 550X4.8MM - NYLON UV\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/index.php\\\/product\\\/cintillo-blanco-550x4-8mm-nylon-uv\\\/#mainImage\"},\"datePublished\":\"2024-07-01T02:25:39+02:00\",\"dateModified\":\"2026-07-11T19:07:02+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/#organization\",\"name\":\"Grupo Yllaconza\",\"description\":\"Sitio Web\",\"url\":\"https:\\\/\\\/grupoyllaconza.pe\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/#website\",\"url\":\"https:\\\/\\\/grupoyllaconza.pe\\\/\",\"name\":\"Grupo Yllaconza\",\"description\":\"Sitio Web\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/grupoyllaconza.pe\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CINTILLO BLANCO 550X4.8MM \u2013 NYLON UV - Grupo Yllaconza","description":"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...","canonical_url":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe#listItem","position":1,"name":"Home","item":"https:\/\/grupoyllaconza.pe","nextItem":{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/shop-2\/#listItem","name":"Shop Page"}},{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/shop-2\/#listItem","position":2,"name":"Shop Page","item":"https:\/\/grupoyllaconza.pe\/index.php\/shop-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product-category\/cintillo-blanco\/#listItem","name":"CINTILLO BLANCO"},"previousItem":{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product-category\/cintillo-blanco\/#listItem","position":3,"name":"CINTILLO BLANCO","item":"https:\/\/grupoyllaconza.pe\/index.php\/product-category\/cintillo-blanco\/","nextItem":{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#listItem","name":"CINTILLO BLANCO 550X4.8MM &#8211; NYLON UV"},"previousItem":{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/shop-2\/#listItem","name":"Shop Page"}},{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#listItem","position":4,"name":"CINTILLO BLANCO 550X4.8MM &#8211; NYLON UV","previousItem":{"@type":"ListItem","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product-category\/cintillo-blanco\/#listItem","name":"CINTILLO BLANCO"}}]},{"@type":"ItemPage","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#itempage","url":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/","name":"CINTILLO BLANCO 550X4.8MM \u2013 NYLON UV - Grupo Yllaconza","description":"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/grupoyllaconza.pe\/#website"},"breadcrumb":{"@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/grupoyllaconza.pe\/wp-content\/uploads\/2026\/07\/CINTILLO-BLANCO-550-X-4.8MM-NYLON-scaled.jpg","@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#mainImage","width":2560,"height":2560,"caption":"CINTILLO BLANCO 550X4.8MM - NYLON UV"},"primaryImageOfPage":{"@id":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/#mainImage"},"datePublished":"2024-07-01T02:25:39+02:00","dateModified":"2026-07-11T19:07:02+02:00"},{"@type":"Organization","@id":"https:\/\/grupoyllaconza.pe\/#organization","name":"Grupo Yllaconza","description":"Sitio Web","url":"https:\/\/grupoyllaconza.pe\/"},{"@type":"WebSite","@id":"https:\/\/grupoyllaconza.pe\/#website","url":"https:\/\/grupoyllaconza.pe\/","name":"Grupo Yllaconza","description":"Sitio Web","inLanguage":"es-ES","publisher":{"@id":"https:\/\/grupoyllaconza.pe\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Grupo Yllaconza - Sitio Web","og:type":"article","og:title":"CINTILLO BLANCO 550X4.8MM \u2013 NYLON UV - Grupo Yllaconza","og:description":"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...","og:url":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/","article:published_time":"2024-07-01T00:25:39+00:00","article:modified_time":"2026-07-11T17:07:02+00:00","twitter:card":"summary_large_image","twitter:title":"CINTILLO BLANCO 550X4.8MM \u2013 NYLON UV - Grupo Yllaconza","twitter:description":"Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ..."},"aioseo_meta_data":{"post_id":"18699","title":null,"description":"#post_excerpt Cintillo blanco 550x4.8mm nylon con excelente resistencia a la tracci\u00f3n. Ideal para instalaciones el\u00e9ctricas, industriales y comerciales ...","keywords":null,"keyphrases":{"focus":{"keyphrase":"CINTILLO BLANCO 550X4.8MM","score":83},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2024-07-01 02:39:35","updated":"2026-08-06 21:52:57","ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":"CINTILLO BLANCO 550X4.8MM","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/grupoyllaconza.pe\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/grupoyllaconza.pe\/index.php\/shop-2\/\" title=\"Shop Page\">Shop Page<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/grupoyllaconza.pe\/index.php\/product-category\/cintillo-blanco\/\" title=\"CINTILLO BLANCO\">CINTILLO BLANCO<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCINTILLO BLANCO 550X4.8MM \u2013 NYLON UV\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/grupoyllaconza.pe"},{"label":"Shop Page","link":"https:\/\/grupoyllaconza.pe\/index.php\/shop-2\/"},{"label":"CINTILLO BLANCO","link":"https:\/\/grupoyllaconza.pe\/index.php\/product-category\/cintillo-blanco\/"},{"label":"CINTILLO BLANCO 550X4.8MM &#8211; NYLON UV","link":"https:\/\/grupoyllaconza.pe\/index.php\/product\/cintillo-blanco-550x4-8mm-nylon-uv\/"}],"_links":{"self":[{"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/product\/18699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/comments?post=18699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/media\/20937"}],"wp:attachment":[{"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/media?parent=18699"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/product_brand?post=18699"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/product_cat?post=18699"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/grupoyllaconza.pe\/index.php\/wp-json\/wp\/v2\/product_tag?post=18699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}